{"id":52163,"date":"2026-07-15T16:57:23","date_gmt":"2026-07-15T19:57:23","guid":{"rendered":"https:\/\/lt15concordia.com.ar\/?p=52163"},"modified":"2026-07-15T16:57:33","modified_gmt":"2026-07-15T19:57:33","slug":"impactante-choque-de-camiones-en-macia-provoco-importantes-danos-materiales","status":"publish","type":"post","link":"https:\/\/lt15concordia.com.ar\/index.php\/2026\/07\/15\/impactante-choque-de-camiones-en-macia-provoco-importantes-danos-materiales\/","title":{"rendered":"Impactante choque de camiones en Maci\u00e1 provoc\u00f3 importantes da\u00f1os materiales"},"content":{"rendered":"\n<p><strong>Dos camiones chocaron de frente en la Ruta Provincial 6, a la altura de Maci\u00e1, sin dejar heridos pero con importantes da\u00f1os materiales<\/strong><\/p>\n\n\n\n<p>Un choque frontal entre dos camiones se registr\u00f3 durante la ma\u00f1ana de este mi\u00e9rcoles sobre la Ruta Provincial N\u00ba 6, a la altura del kil\u00f3metro 144, en jurisdicci\u00f3n de Maci\u00e1, departamento Tala.<\/p>\n\n\n\n<p>Seg\u00fan inform\u00f3 la Polic\u00eda, el choque se registr\u00f3 cerca de las 7, e involucr\u00f3 a un cami\u00f3n Volvo con semirremolque de origen brasile\u00f1o, cargado con cosm\u00e9ticos y conducido por un hombre de 39 a\u00f1os, que circulaba en sentido sur, y un cami\u00f3n Iveco con chasis y acoplado, cargado con papas, guiado por un hombre de 47 a\u00f1os, oriundo de La Paz, que transitaba en sentido contrario. Los veh\u00edculos colisionaron de frente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"p-1784121978637-81829\">Sin lesionados<\/h2>\n\n\n\n<p id=\"p-1784121642332-72239\">A pesar de la magnitud del impacto, no se registraron personas lesionadas, report\u00e1ndose \u00fanicamente importantes da\u00f1os materiales.<\/p>\n\n\n\n<p id=\"p-1784121642332-65791\">Como consecuencia del choque, el acoplado de uno de los camiones qued\u00f3 atravesado sobre la calzada, por lo que el tr\u00e1nsito permanec\u00eda esta ma\u00f1ana asistido y reducido a un solo carril, mientras se desarrollaban las tareas para retirar los veh\u00edculos. En el operativo trabaj\u00f3 personal de las comisar\u00edas de Maci\u00e1, Durazno y Guardamonte, junto a efectivos de la Direcci\u00f3n General de Prevenci\u00f3n y Seguridad Vial, puesto Tala, consign\u00f3 el sitio\u00a0<em>El Uruguayense<\/em>.<\/p>\n\n\n\n<p>Fuente: Diario Uno Entre R\u00edos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos camiones chocaron de frente en la Ruta Provincial 6, a la altura de Maci\u00e1, sin dejar heridos pero con importantes da\u00f1os materiales Un choque frontal entre dos camiones se registr\u00f3 durante la ma\u00f1ana de este mi\u00e9rcoles sobre la Ruta Provincial N\u00ba 6, a la altura del kil\u00f3metro 144, en jurisdicci\u00f3n de Maci\u00e1, departamento Tala. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":52164,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"_links":{"self":[{"href":"https:\/\/lt15concordia.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52163"}],"collection":[{"href":"https:\/\/lt15concordia.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lt15concordia.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lt15concordia.com.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lt15concordia.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=52163"}],"version-history":[{"count":1,"href":"https:\/\/lt15concordia.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52163\/revisions"}],"predecessor-version":[{"id":52165,"href":"https:\/\/lt15concordia.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52163\/revisions\/52165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lt15concordia.com.ar\/index.php\/wp-json\/wp\/v2\/media\/52164"}],"wp:attachment":[{"href":"https:\/\/lt15concordia.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=52163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lt15concordia.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=52163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lt15concordia.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=52163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}